{"id":24498,"date":"2024-12-11T12:22:21","date_gmt":"2024-12-11T11:22:21","guid":{"rendered":"https:\/\/talking-hope.org\/?p=24498"},"modified":"2024-12-11T12:44:58","modified_gmt":"2024-12-11T11:44:58","slug":"lets_have_a_dream","status":"publish","type":"post","link":"https:\/\/talking-hope.org\/de\/lets_have_a_dream\/","title":{"rendered":"LET\u2019S HAVE A DREAM"},"content":{"rendered":"<div class=\"gb-container gb-container-92291a49\">\n<div class=\"gb-container gb-container-bb5c9806\">\n<div class=\"gb-container gb-container-b1cf4801\">\n\n<h1 class=\"wp-block-heading has-text-align-center has-accent-2-color has-text-color\" style=\"font-size:52px\">\u201eLET\u2019S HAVE A DREAM\u201c<br><br><\/h1>\n\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-8a1dfe02\">\n<div class=\"gb-container gb-container-923a08a4\">\n<div class=\"gb-container gb-container-77f86f1e\">\n\n<figure class=\"gb-block-image gb-block-image-61ca27c0\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" class=\"gb-image gb-image-61ca27c0\" src=\"https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK.png?resize=800%2C800&#038;ssl=1\" alt=\"\" title=\"MLK\" srcset=\"https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK.png?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK.png?resize=12%2C12&amp;ssl=1 12w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<\/div>\n<\/div>\n<div class=\"gb-shapes\"><div class=\"gb-shape gb-shape-1\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1200 350\" preserveaspectratio=\"none\"><path d=\"M1200 350V0C22.4 60.3 0 336.7 0 336.7V350h1200z\"\/><\/svg><\/div><\/div><\/div>\n\n<div class=\"gb-container gb-container-82c316e6\">\n<div class=\"gb-container gb-container-300056bd\">\n<div class=\"gb-container gb-container-3faa05af\">\n\n<h1 class=\"gb-headline gb-headline-a4669590 gb-headline-text\"><strong>Heute vor 60 Jahren wurde Dr. Martin Luther King <\/strong><br><strong>der Friedensnobelpreis verliehen<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Von Jenny Bischofberger<\/em><\/p>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Das bekannte Zitat, das mich zu diesem Text inspiriert hat, stammt aus Martin Luther Kings ber\u00fchmter Rede vor 250.000 Demonstrierenden im August 1963 in Washington D.C.: Der Satz stand noch nicht einmal in seinem Skript, es war das spontan improvisierte Finale, das Martin Luther King dann weiter wiederholte wie den Refrain eines Liedes: <em>\u201cI have a dream\u2026\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Traum von Martin Luther King bezog sich auf seine Kinder:<br><em>\u201eI have a dream that my four little children will one day live in a nation where they will not be judged by the color of their skin but by the content of their character.\u201c<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">King malte in diesem Teil der Rede eine Gesellschaft der Zukunft aus, in der sich Schwarze und Wei\u00dfe die Hand geben und gemeinsam die Zukunft gestalten k\u00f6nnen. Sein Utopia war keine gesichtslose Zukunft.\n<\/br><\/br>\nEs war die Vision einer besseren und friedlichen Zukunft f\u00fcr seine und alle Kinder Amerikas. Er platzierte diese Vision inmitten einer Gesellschaft, in der Segregation und Rassismus den Status Quo ausmachten. Die USA schien von einer sozialen, \u00f6konomischen, politischen und rechtlichen Gleichstellung von Schwarzen und Wei\u00dfen damals noch sehr weit entfernt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martin Luther King wurde mit seiner rhetorischen Meisterleistung als ein \u201eSouver\u00e4n der Situation\u201c beschrieben, als empathisch und enthusiastisch gleicherma\u00dfen. Seine Personifizierung von Zukunft auf die Kinder transportierten keine abstrakten politischen Ziele, sondern erz\u00e4hlten diese pers\u00f6nlich und strahlten Gerechtigkeitssinn und Liebe aus. Eine Liebe, die Mitmenschen achtet und sich ihnen mit Geduld zuneigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zukunftssorge ist (Eltern)f\u00fcrsorge<\/strong><br>Bis heute sp\u00fcren wir das Wirken von Martin Luther King. Seine Zukunftsvision und sein unerm\u00fcdlicher Kampf f\u00fcr Gleichheit und Gerechtigkeit haben die B\u00fcrgerrechtsbewegung vorangetrieben, doch viel mehr als das. Mit seinem Blick auf die Zukunft auch als das \u201eLeben unserer Kinder\u201c setzte er Verantwortung f\u00fcr Gesellschaft und Politik gleich mit der F\u00fcrsorge liebender Eltern f\u00fcr ihre Kinder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und aus diesem Blickwinkel heraus schaffte er es denn auch die Wei\u00dfen eben nicht als Gegner, sondern als Br\u00fcder und Schwestern anzusprechen, deren Schicksal als gemeinsame Familienmitglieder untrennbar mit dem der Schwarzen verbunden war:<br><em>\u201cOur white brothers, as evidenced by their presence here today, have come to realize that their destiny is tied up with our destiny.\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hoffnung als Handlungsauftrag<\/strong><br>Zukunft, das war f\u00fcr King damit nicht nur eine pers\u00f6nliche Geschichte f\u00fcr jede einzelne Familie. Zukunft war f\u00fcr ihn auch die Aufgabe einer gro\u00dfen Menschheitsfamilie, in die er alle Menschen einbezog. Hoffnung f\u00fcr diese bessere Zukunft wurde damit ein klarer Handlungsauftrag. Gesellschaftliches und politisches Engagement ist Engagement f\u00fcr unsere und unser aller Kinder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bis heute geht von Kings Rede f\u00fcr viele Menschen eine gro\u00dfe Kraft der Hoffnung aus \u2013 auch f\u00fcr mich. Die Zugkraft von Hoffnung ist vielleicht gerade dann am Tragendsten, wenn sie eben schwerf\u00e4llt.<\/p>\n\n\n<div class=\"gb-container gb-container-db0501c4\">\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_small.jpg?resize=1200%2C801&#038;ssl=1\" alt=\"\" class=\"wp-image-24500\" style=\"width:852px;height:auto\" srcset=\"https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_small.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_small.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_small.jpg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_small.jpg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_small.jpg?resize=18%2C12&amp;ssl=1 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Das&nbsp;<em>Stone of Hope<\/em>&nbsp;at the Martin Luther King, Jr. Memorial &#8211; Washington, D.C.<\/figcaption><\/figure>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Den Kindern beim Entdecken der Welt zuschauen<\/strong><br>Mein Vater ist vor 20 Jahren an Amyotropher Lateralsklerose (ALS), einer Erkrankung des Nervensystems, gestorben. Sein wacher Geist musste drei Jahre in einem sterbenden K\u00f6rper leben. Der Vater meiner eigenen drei Kinder ist mit 51 Jahren an Krebs gestorben. Auch er hatte die Kraft, drei Jahre in einem \u2013 aus medizinischer Sicht - nicht mehr lebensf\u00e4higen K\u00f6rper zu Leben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr beide gab es keine Hoffnung auf ein \u00dcberleben. Doch Hoffnung sah ich trotzdem in ihren Augen \u2013 und zwar immer dann, wenn sie ihren Kindern beim Entdecken der Welt zuschauen konnten. Hoffnung geht weit \u00fcber eine Krise oder den Tod hinaus: Wir k\u00f6nnen sie im Leben unserer Kinder sehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Erfahrung hat mich gelehrt, dass Hoffnung weit \u00fcber individuelle Schicksale hinausreicht. Sie zeigt sich in den Augen unserer Kinder und in einer Vision f\u00fcr ihre Zukunft \u2013 die Art von Vision, die Martin Luther King in seiner \u201eI have a dream\u201c-Rede so kraftvoll beschrieben hat. <em>\u201cI have a dream\u201d<\/em>-speech.<\/p>\n\n\n\n<p class=\"has-var-aubergine-color has-text-color wp-block-paragraph\"><strong>Auf dem Weg vom Ist- zum Soll-Zustand<\/strong><br>King hat diese \u00dcberzeugung niemals aufgegeben, obwohl er wusste, dass er sich in gro\u00dfer Gefahr befand. F\u00fcnf Jahre, nachdem er den Friedensnobelpreis entgegengenommen hatte, wurde er im Alter von nur 39 Jahren am 4. April 1968 aus rassistischen Motiven in einem Attentat in Memphis, Tennessee, ermordet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Reaktion auf das Attentat sagte ein Weggef\u00e4hrte \u00fcber sein Wirken:<br><em>\u201e\u2026this nation has to be challenged and transformed from what it is to what it ought to be.\u201c (\u201ediese Nation muss herausgefordert und umgestaltet werden auf dem Weg von Ihrem Ist-Zustand zu dem, was sie sein sollte.\u201c)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martin Luther Kings gewaltloser Kampf f\u00fcr Gerechtigkeit, kann uns heute auf dem Weg in eine klimaneutrale, sozial gerechtere Zukunft begleiten. Seine Botschaft von Hoffnung war weder idealistisch noch abstrakt, sondern tief in menschlichen Erfahrungen und Bed\u00fcrfnissen verwurzelt. An Visionen festzuhalten und sie zugleich zu teilen und selbst Gegner und Verhinderer in sie einzubeziehen, ist eine weitere wichtige Botschaft f\u00fcr die heutige Transformation zu nachhaltigen Lebensweisen.<\/p>\n\n\n\n<p class=\"has-var-aubergine-color has-text-color wp-block-paragraph\"><strong>Wie kommunizieren?<\/strong><br>Was hei\u00dft das konkret? Wir k\u00f6nnen aus Kings hoffnungsvollem Ansatz lernen und uns von ihm inspirieren lassen. Mir sind daf\u00fcr drei Kernpunkte wichtig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Erstens m\u00fcssen wir \u00fcber den Status Quo sprechen. King sagte klar: \u201eThe negro is still not free.\u201c Heute ist es wichtig, breiteres Bewusstsein f\u00fcr das Ausma\u00df der Klimakrise und ihre existenzgef\u00e4hrdenden Auswirkungen zu schaffen. So k\u00f6nnen wir die pers\u00f6nliche Distanz vieler zu einem \u00fcberw\u00e4ltigend erscheinenden Thema verringern und die Situation greifbarer machen.<\/p>\n\n\n\n<p class=\"has-var-aubergine-color has-text-color wp-block-paragraph\"><b>Die M\u00fchen der Ver\u00e4nderung<\/b><\/br>\nZweitens ist es wichtig zu kommunizieren, wie eine Zukunft ohne oder ohne ausreichende Anpassung aussehen w\u00fcrde, wenn wir also nichts oder zu wenig tun, um die Klimakrise einzud\u00e4mmen und uns als Menschen auf ihre Folgen vorzubereiten. King begn\u00fcgte sich nicht damit, auf eine utopische Zukunft zu verweisen. Er sprach auch die konkreten Bedingungen daf\u00fcr an \u2013 wie etwa das Ende von Polizeigewalt gegen\u00fcber Schwarzen. <\/p>\nGleichzeitig darf es nicht dabeibleiben, die M\u00fchen der Ver\u00e4nderung zu thematisieren oder Dystopien auszumalen, sollten diese gescheut werden. Apokalyptisch anma\u00dfende Metaphern \u00fcberfordern und ver\u00e4ngstigen viele Menschen und k\u00f6nnen damit zu einem l\u00e4hmenden \u201eIch kann ja eh nichts tun\u201c f\u00fchren.<br><br><strong>\u201ePositive Nebenwirkungen\u201c<\/strong><br>Martin Luther King malte in seiner Traumrede eine einladende Zukunftsvision aus. Auf heute bezogen bedeutet dies, dass wir - drittens - aufzeigen, welche Chancen eine umfassende nachhaltige Gestaltung unserer Gesellschaft f\u00fcr uns Menschen birgt. Hier geht es nicht um Optimismus im Sinne von \u201eEs wird schon alles gut, und die anderen werden sich k\u00fcmmern.\u201c Es geht vielmehr um die positive \u201eNebenwirkungen\u201c, die Nachhaltigkeit und Klimaschutz f\u00fcr unser Leben bieten \u2013 f\u00fcr unsere Gesundheit, f\u00fcr ein sozialeres Miteinander, f\u00fcr eine innovative Wirtschaft, f\u00fcr gerechtere Gesellschaften und internationale Beziehungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martin Luther King kann als Inspiration daf\u00fcr dienen, wie wir die heutige Zukunftsgeschichte zugleich dringlich und einladend erz\u00e4hlen k\u00f6nnen. Mit Emotionen, die die Botschaft von Selbstwirksamkeit mit gutem \u201eStorytelling\u201c und sogar Humor verbinden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Martin Luthers Kings \u201eZukunftsscheck\u201c heute<\/strong><br>King bot seinen Zuh\u00f6rer*innen in Washington einen \u201eScheck\u201c \u00fcber die Zukunft an, der den Menschen in einem gleichberechtigten Amerika ohne Rassismus winken w\u00fcrde: <em>\u201eAnd so, we've come to cash this check, a check that will give us upon demand the riches of freedom and the security of justice....\u201c (\u201eein Scheck, der uns auf Verlangen die Reicht\u00fcmer der Freiheit und die Sicherheit der Gerechtigkeit bieten wird\u201c).<\/em><\/p>\n\n\n\n<p class=\"has-var-aubergine-color has-text-color wp-block-paragraph\">Ich w\u00fcnsche meinen \u2013 und allen anderen \u2013 Kindern den Scheck der Nachhaltigkeit, der mehr Sicherheit, mehr Gesundheit, mehr Gerechtigkeit \u2013 und damit mehr Lebensqualit\u00e4t - verspricht. Klimaschutz ist F\u00fcrsorge f\u00fcr zuk\u00fcnftige Generationen, f\u00fcr unsere Kinder \u2013 und auch Martin Luther Kings Kindes- und Kindeskinder.<\/p>\n\n\n<div class=\"gb-container gb-container-48f5c1a5\">\n<div class=\"gb-container gb-container-7a8bc1b1\">\n\n<p class=\"gb-headline gb-headline-e8bfe6ff gb-headline-text\">Diesen Beitrag teilen:<\/p>\n\n\n\n<ul class=\"wp-block-social-links is-content-justification-left is-layout-flex wp-container-core-social-links-is-layout-63375db1 wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-mastodon wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/talking-hope.org\/de\/lets_have_a_dream\/?share=mastodon&#038;nb=1\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M23.193 7.879c0-5.206-3.411-6.732-3.411-6.732C18.062.357 15.108.025 12.041 0h-.076c-3.068.025-6.02.357-7.74 1.147 0 0-3.411 1.526-3.411 6.732 0 1.192-.023 2.618.015 4.129.124 5.092.934 10.109 5.641 11.355 2.17.574 4.034.695 5.535.612 2.722-.15 4.25-.972 4.25-.972l-.09-1.975s-1.945.613-4.129.539c-2.165-.074-4.449-.233-4.799-2.891a5.499 5.499 0 0 1-.048-.745s2.125.52 4.817.643c1.646.075 3.19-.097 4.758-.283 3.007-.359 5.625-2.212 5.954-3.905.517-2.665.475-6.507.475-6.507zm-4.024 6.709h-2.497V8.469c0-1.29-.543-1.944-1.628-1.944-1.2 0-1.802.776-1.802 2.312v3.349h-2.483v-3.35c0-1.536-.602-2.312-1.802-2.312-1.085 0-1.628.655-1.628 1.944v6.119H4.832V8.284c0-1.289.328-2.313.987-3.07.68-.758 1.569-1.146 2.674-1.146 1.278 0 2.246.491 2.886 1.474L12 6.585l.622-1.043c.64-.983 1.608-1.474 2.886-1.474 1.104 0 1.994.388 2.674 1.146.658.757.986 1.781.986 3.07v6.304z\"\/><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Mastodon<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-linkedin wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/talking-hope.org\/de\/lets_have_a_dream\/?share=linkedin&#038;nb=1\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19.7,3H4.3C3.582,3,3,3.582,3,4.3v15.4C3,20.418,3.582,21,4.3,21h15.4c0.718,0,1.3-0.582,1.3-1.3V4.3 C21,3.582,20.418,3,19.7,3z M8.339,18.338H5.667v-8.59h2.672V18.338z M7.004,8.574c-0.857,0-1.549-0.694-1.549-1.548 c0-0.855,0.691-1.548,1.549-1.548c0.854,0,1.547,0.694,1.547,1.548C8.551,7.881,7.858,8.574,7.004,8.574z M18.339,18.338h-2.669 v-4.177c0-0.996-0.017-2.278-1.387-2.278c-1.389,0-1.601,1.086-1.601,2.206v4.249h-2.667v-8.59h2.559v1.174h0.037 c0.356-0.675,1.227-1.387,2.526-1.387c2.703,0,3.203,1.779,3.203,4.092V18.338z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">LinkedIn<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-twitter wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/talking-hope.org\/de\/lets_have_a_dream\/?share=twitter&#038;nb=1\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M22.23,5.924c-0.736,0.326-1.527,0.547-2.357,0.646c0.847-0.508,1.498-1.312,1.804-2.27 c-0.793,0.47-1.671,0.812-2.606,0.996C18.324,4.498,17.257,4,16.077,4c-2.266,0-4.103,1.837-4.103,4.103 c0,0.322,0.036,0.635,0.106,0.935C8.67,8.867,5.647,7.234,3.623,4.751C3.27,5.357,3.067,6.062,3.067,6.814 c0,1.424,0.724,2.679,1.825,3.415c-0.673-0.021-1.305-0.206-1.859-0.513c0,0.017,0,0.034,0,0.052c0,1.988,1.414,3.647,3.292,4.023 c-0.344,0.094-0.707,0.144-1.081,0.144c-0.264,0-0.521-0.026-0.772-0.074c0.522,1.63,2.038,2.816,3.833,2.85 c-1.404,1.1-3.174,1.756-5.096,1.756c-0.331,0-0.658-0.019-0.979-0.057c1.816,1.164,3.973,1.843,6.29,1.843 c7.547,0,11.675-6.252,11.675-11.675c0-0.178-0.004-0.355-0.012-0.531C20.985,7.47,21.68,6.747,22.23,5.924z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Twitter<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-mail wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"mailto:?subject=LET\u2019S%20%20HAVE%20A%20DREAM&#038;body=https:\/\/talking-hope.org\/lets_have_a_dream\/&#038;share=email&#038;nb=1\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">E-Mail<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-facebook wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/talking-hope.org\/de\/lets_have_a_dream\/?share=facebook&#038;nb=1\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-whatsapp wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/talking-hope.org\/de\/lets_have_a_dream\/?share=jetpack-whatsapp&#038;nb=1\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M 12.011719 2 C 6.5057187 2 2.0234844 6.478375 2.0214844 11.984375 C 2.0204844 13.744375 2.4814687 15.462563 3.3554688 16.976562 L 2 22 L 7.2324219 20.763672 C 8.6914219 21.559672 10.333859 21.977516 12.005859 21.978516 L 12.009766 21.978516 C 17.514766 21.978516 21.995047 17.499141 21.998047 11.994141 C 22.000047 9.3251406 20.962172 6.8157344 19.076172 4.9277344 C 17.190172 3.0407344 14.683719 2.001 12.011719 2 z M 12.009766 4 C 14.145766 4.001 16.153109 4.8337969 17.662109 6.3417969 C 19.171109 7.8517969 20.000047 9.8581875 19.998047 11.992188 C 19.996047 16.396187 16.413812 19.978516 12.007812 19.978516 C 10.674812 19.977516 9.3544062 19.642812 8.1914062 19.007812 L 7.5175781 18.640625 L 6.7734375 18.816406 L 4.8046875 19.28125 L 5.2851562 17.496094 L 5.5019531 16.695312 L 5.0878906 15.976562 C 4.3898906 14.768562 4.0204844 13.387375 4.0214844 11.984375 C 4.0234844 7.582375 7.6067656 4 12.009766 4 z M 8.4765625 7.375 C 8.3095625 7.375 8.0395469 7.4375 7.8105469 7.6875 C 7.5815469 7.9365 6.9355469 8.5395781 6.9355469 9.7675781 C 6.9355469 10.995578 7.8300781 12.182609 7.9550781 12.349609 C 8.0790781 12.515609 9.68175 15.115234 12.21875 16.115234 C 14.32675 16.946234 14.754891 16.782234 15.212891 16.740234 C 15.670891 16.699234 16.690438 16.137687 16.898438 15.554688 C 17.106437 14.971687 17.106922 14.470187 17.044922 14.367188 C 16.982922 14.263188 16.816406 14.201172 16.566406 14.076172 C 16.317406 13.951172 15.090328 13.348625 14.861328 13.265625 C 14.632328 13.182625 14.464828 13.140625 14.298828 13.390625 C 14.132828 13.640625 13.655766 14.201187 13.509766 14.367188 C 13.363766 14.534188 13.21875 14.556641 12.96875 14.431641 C 12.71875 14.305641 11.914938 14.041406 10.960938 13.191406 C 10.218937 12.530406 9.7182656 11.714844 9.5722656 11.464844 C 9.4272656 11.215844 9.5585938 11.079078 9.6835938 10.955078 C 9.7955938 10.843078 9.9316406 10.663578 10.056641 10.517578 C 10.180641 10.371578 10.223641 10.267562 10.306641 10.101562 C 10.389641 9.9355625 10.347156 9.7890625 10.285156 9.6640625 C 10.223156 9.5390625 9.737625 8.3065 9.515625 7.8125 C 9.328625 7.3975 9.131125 7.3878594 8.953125 7.3808594 C 8.808125 7.3748594 8.6425625 7.375 8.4765625 7.375 z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">WhatsApp<\/span><\/a><\/li><\/ul>\n\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gb-shapes\"><div class=\"gb-shape gb-shape-1\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1200 194.3\" preserveaspectratio=\"none\"><path d=\"M1200 133.3l-50 8.9c-50 8.6-150 26.9-250 31.1-100 4.2-200-4.2-300-26.7S400 89.2 300 62.2C200 35.8 100 17.5 50 8.9L0 0v194.3h1200v-61z\"\/><\/svg><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u201eLET\u2019S HAVE A DREAM\u201c Martin Luther King Jr. was awarded the Nobel Peace Prize 60 years ago today By Jenny &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"LET\u2019S HAVE A DREAM\" class=\"read-more button\" href=\"https:\/\/talking-hope.org\/de\/lets_have_a_dream\/#more-24498\" aria-label=\"Mehr Informationen \u00fcber LET\u2019S HAVE A DREAM\">Read more<\/a><\/p>","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"MARTIN LUTHER KING CAN INSPIRE OUR CLIMATE COMMUNICATION","_seopress_titles_desc":"60 years ago, Martin Luther King was awarded the Nobel Peace Prize. In his famous \u201cI have a dream\u201d speech, he envisioned a peaceful future for his children and all the children of America. By equating societal and political responsibility with the care that loving parents provide for their children, King made the future a shared endeavor for all citizens. His approach can inspire us in the transition to a sustainable future.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"https:\/\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_social.png","_seopress_social_fb_img_attachment_id":24505,"_seopress_social_fb_img_width":3280,"_seopress_social_fb_img_height":1712,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"https:\/\/talking-hope.org\/wp-content\/uploads\/2024\/12\/MLK_social.png","_seopress_social_twitter_img_attachment_id":24505,"_seopress_social_twitter_img_width":3280,"_seopress_social_twitter_img_height":1712,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8,9,10],"tags":[],"class_list":["post-24498","post","type-post","status-publish","format-standard","hentry","category-climate","category-democracy","category-justice","no-featured-image-padding"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":false,"_links":{"self":[{"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/posts\/24498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/comments?post=24498"}],"version-history":[{"count":5,"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/posts\/24498\/revisions"}],"predecessor-version":[{"id":24512,"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/posts\/24498\/revisions\/24512"}],"wp:attachment":[{"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/media?parent=24498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/categories?post=24498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/talking-hope.org\/de\/wp-json\/wp\/v2\/tags?post=24498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}